{"id":652,"date":"2022-04-07T20:07:14","date_gmt":"2022-04-07T20:07:14","guid":{"rendered":"https:\/\/dorontash.com\/en\/?post_type=product&#038;p=652"},"modified":"2022-04-28T09:44:54","modified_gmt":"2022-04-28T09:44:54","slug":"abtin-mirror-and-key-hanger","status":"publish","type":"product","link":"https:\/\/dorontash.com\/en\/product\/abtin-mirror-and-key-hanger\/","title":{"rendered":"abtin mirror and key hanger"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":828,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[31,32,34],"product_tag":[],"class_list":{"0":"post-652","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-traditional-decoration","7":"product_cat-traditional-keychain","8":"product_cat-traditional-mirrors","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>traditional mirror and key hanger - dorontash iran handicrafts<\/title>\n<meta name=\"description\" content=\"traditional mirror and key hanger, souvenirs, artistic and traditional decorations, decorate children&#039;s rooms, dorontash store is in iran\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorontash.com\/product\/wall-traditional-mirror-abtin-5074\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"traditional mirror and key hanger - dorontash iran handicrafts\" \/>\n<meta property=\"og:description\" content=\"traditional mirror and key hanger, souvenirs, artistic and traditional decorations, decorate children&#039;s rooms, dorontash store is in iran\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorontash.com\/product\/wall-traditional-mirror-abtin-5074\/\" \/>\n<meta property=\"og:site_name\" content=\"Dorontash\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-28T09:44:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dorontash.com\/en\/wp-content\/uploads\/2022\/04\/abtin-mirror-key-wall-face.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorontash.com\\\/en\\\/product\\\/abtin-mirror-and-key-hanger\\\/\",\"url\":\"https:\\\/\\\/dorontash.com\\\/product\\\/wall-traditional-mirror-abtin-5074\\\/\",\"name\":\"traditional mirror and key hanger - dorontash iran handicrafts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorontash.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorontash.com\\\/product\\\/wall-traditional-mirror-abtin-5074\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorontash.com\\\/product\\\/wall-traditional-mirror-abtin-5074\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorontash.com\\\/en\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/abtin-mirror-key-wall-face.jpg\",\"datePublished\":\"2022-04-07T20:07:14+00:00\",\"dateModified\":\"2022-04-28T09:44:54+00:00\",\"description\":\"traditional mirror and key hanger, souvenirs, artistic and traditional decorations, decorate children's rooms, dorontash store is in iran\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorontash.com\\\/product\\\/wall-traditional-mirror-abtin-5074\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorontash.com\\\/product\\\/wall-traditional-mirror-abtin-5074\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dorontash.com\\\/product\\\/wall-traditional-mirror-abtin-5074\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorontash.com\\\/en\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/abtin-mirror-key-wall-face.jpg\",\"contentUrl\":\"https:\\\/\\\/dorontash.com\\\/en\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/abtin-mirror-key-wall-face.jpg\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorontash.com\\\/product\\\/wall-traditional-mirror-abtin-5074\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dorontash.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/dorontash.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"abtin mirror and key hanger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorontash.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/dorontash.com\\\/en\\\/\",\"name\":\"Dorontash\",\"description\":\"Dorontash Crafts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorontash.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"traditional mirror and key hanger - dorontash iran handicrafts","description":"traditional mirror and key hanger, souvenirs, artistic and traditional decorations, decorate children's rooms, dorontash store is in iran","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorontash.com\/product\/wall-traditional-mirror-abtin-5074\/","og_locale":"en_US","og_type":"article","og_title":"traditional mirror and key hanger - dorontash iran handicrafts","og_description":"traditional mirror and key hanger, souvenirs, artistic and traditional decorations, decorate children's rooms, dorontash store is in iran","og_url":"https:\/\/dorontash.com\/product\/wall-traditional-mirror-abtin-5074\/","og_site_name":"Dorontash","article_modified_time":"2022-04-28T09:44:54+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/dorontash.com\/en\/wp-content\/uploads\/2022\/04\/abtin-mirror-key-wall-face.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dorontash.com\/en\/product\/abtin-mirror-and-key-hanger\/","url":"https:\/\/dorontash.com\/product\/wall-traditional-mirror-abtin-5074\/","name":"traditional mirror and key hanger - dorontash iran handicrafts","isPartOf":{"@id":"https:\/\/dorontash.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorontash.com\/product\/wall-traditional-mirror-abtin-5074\/#primaryimage"},"image":{"@id":"https:\/\/dorontash.com\/product\/wall-traditional-mirror-abtin-5074\/#primaryimage"},"thumbnailUrl":"https:\/\/dorontash.com\/en\/wp-content\/uploads\/2022\/04\/abtin-mirror-key-wall-face.jpg","datePublished":"2022-04-07T20:07:14+00:00","dateModified":"2022-04-28T09:44:54+00:00","description":"traditional mirror and key hanger, souvenirs, artistic and traditional decorations, decorate children's rooms, dorontash store is in iran","breadcrumb":{"@id":"https:\/\/dorontash.com\/product\/wall-traditional-mirror-abtin-5074\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorontash.com\/product\/wall-traditional-mirror-abtin-5074\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dorontash.com\/product\/wall-traditional-mirror-abtin-5074\/#primaryimage","url":"https:\/\/dorontash.com\/en\/wp-content\/uploads\/2022\/04\/abtin-mirror-key-wall-face.jpg","contentUrl":"https:\/\/dorontash.com\/en\/wp-content\/uploads\/2022\/04\/abtin-mirror-key-wall-face.jpg","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/dorontash.com\/product\/wall-traditional-mirror-abtin-5074\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dorontash.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/dorontash.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"abtin mirror and key hanger"}]},{"@type":"WebSite","@id":"https:\/\/dorontash.com\/en\/#website","url":"https:\/\/dorontash.com\/en\/","name":"Dorontash","description":"Dorontash Crafts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorontash.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dorontash.com\/en\/wp-json\/wp\/v2\/product\/652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorontash.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dorontash.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/dorontash.com\/en\/wp-json\/wp\/v2\/comments?post=652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorontash.com\/en\/wp-json\/wp\/v2\/media\/828"}],"wp:attachment":[{"href":"https:\/\/dorontash.com\/en\/wp-json\/wp\/v2\/media?parent=652"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dorontash.com\/en\/wp-json\/wp\/v2\/product_brand?post=652"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dorontash.com\/en\/wp-json\/wp\/v2\/product_cat?post=652"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dorontash.com\/en\/wp-json\/wp\/v2\/product_tag?post=652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}